{"id":957,"date":"2021-09-03T12:25:44","date_gmt":"2021-09-03T10:25:44","guid":{"rendered":"https:\/\/konzertfreunde.com\/eventos\/registro\/"},"modified":"2025-02-15T14:45:04","modified_gmt":"2025-02-15T13:45:04","slug":"registro","status":"publish","type":"page","link":"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/","title":{"rendered":"Registro"},"content":{"rendered":"<span class=\"error\">Some\u00adthing wrong. Try&nbsp;again<\/span>\n\n\n\n<div style=\"height:4433px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":124,"featured_media":0,"parent":955,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"wp_typography_post_enhancements_disabled":false,"ngg_post_thumbnail":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-957","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Registro - Konzertfreunde Costa Blanca<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Registro - Konzertfreunde Costa Blanca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/\" \/>\n<meta property=\"og:site_name\" content=\"Konzertfreunde Costa Blanca\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/groups\/konzertfreundecostablanca\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-15T13:45:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/eventos\\\/registro\\\/\",\"url\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/eventos\\\/registro\\\/\",\"name\":\"Registro - Konzertfreunde Costa Blanca\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/#website\"},\"datePublished\":\"2021-09-03T10:25:44+00:00\",\"dateModified\":\"2025-02-15T13:45:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/eventos\\\/registro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/eventos\\\/registro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/eventos\\\/registro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/veranstaltungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Registro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/\",\"name\":\"Konzertfreunde Costa Blanca\",\"description\":\"Kultur an der Costa Blanca\",\"publisher\":{\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/#organization\",\"name\":\"Konzertfreunde Costa Blanca\",\"url\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/konzertfreunde.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/weblogo.jpg\",\"contentUrl\":\"https:\\\/\\\/konzertfreunde.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/weblogo.jpg\",\"width\":500,\"height\":146,\"caption\":\"Konzertfreunde Costa Blanca\"},\"image\":{\"@id\":\"https:\\\/\\\/konzertfreunde.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/groups\\\/konzertfreundecostablanca\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Registro - Konzertfreunde Costa Blanca","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/","og_locale":"es_ES","og_type":"article","og_title":"Registro - Konzertfreunde Costa Blanca","og_url":"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/","og_site_name":"Konzertfreunde Costa Blanca","article_publisher":"https:\/\/www.facebook.com\/groups\/konzertfreundecostablanca","article_modified_time":"2025-02-15T13:45:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/","url":"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/","name":"Registro - Konzertfreunde Costa Blanca","isPartOf":{"@id":"https:\/\/konzertfreunde.com\/es\/#website"},"datePublished":"2021-09-03T10:25:44+00:00","dateModified":"2025-02-15T13:45:04+00:00","breadcrumb":{"@id":"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/konzertfreunde.com\/es\/eventos\/registro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/konzertfreunde.com\/es\/eventos\/registro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/konzertfreunde.com\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/konzertfreunde.com\/es\/veranstaltungen\/"},{"@type":"ListItem","position":3,"name":"Registro"}]},{"@type":"WebSite","@id":"https:\/\/konzertfreunde.com\/es\/#website","url":"https:\/\/konzertfreunde.com\/es\/","name":"Konzertfreunde Costa Blanca","description":"Kultur an der Costa Blanca","publisher":{"@id":"https:\/\/konzertfreunde.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/konzertfreunde.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/konzertfreunde.com\/es\/#organization","name":"Konzertfreunde Costa Blanca","url":"https:\/\/konzertfreunde.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/konzertfreunde.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/konzertfreunde.com\/wp-content\/uploads\/2021\/09\/weblogo.jpg","contentUrl":"https:\/\/konzertfreunde.com\/wp-content\/uploads\/2021\/09\/weblogo.jpg","width":500,"height":146,"caption":"Konzertfreunde Costa Blanca"},"image":{"@id":"https:\/\/konzertfreunde.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/groups\/konzertfreundecostablanca"]}]}},"_links":{"self":[{"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/pages\/957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/users\/124"}],"replies":[{"embeddable":true,"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/comments?post=957"}],"version-history":[{"count":3,"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/pages\/957\/revisions"}],"predecessor-version":[{"id":7939,"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/pages\/957\/revisions\/7939"}],"up":[{"embeddable":true,"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/pages\/955"}],"wp:attachment":[{"href":"https:\/\/konzertfreunde.com\/es\/wp-json\/wp\/v2\/media?parent=957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}